{"id":10926,"date":"2024-05-23T09:46:16","date_gmt":"2024-05-23T09:46:16","guid":{"rendered":"https:\/\/www.yesco.com\/lasvegas-testing\/marquee-repair-at-bellagio-hotel-casino\/"},"modified":"2024-09-10T20:16:51","modified_gmt":"2024-09-10T20:16:51","slug":"marquee-repair-at-bellagio-hotel-casino","status":"publish","type":"post","link":"https:\/\/www.yesco.com\/lasvegas\/marquee-repair-at-bellagio-hotel-casino\/","title":{"rendered":"Marquee Repair at Bellagio Hotel &amp; Casino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">It&#8217;s just not right when the IO in your name isn&#8217;t illuminated.  YESCO techs arrived on site at the Bellagio Hotel and Casino in Las Vegas and found there was no power leading to the letters.  Quickly found a defective power supply was the problem.  No worries.  It was easily replaced and the sign is now operating at 100%. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" data-id=\"11177\" src=\"https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before.jpg\" alt=\"\" class=\"wp-image-11177\" srcset=\"https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before.jpg 1536w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before-768x1024.jpg 768w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before-1152x1536.jpg 1152w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before-640x853.jpg 640w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before-400x533.jpg 400w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/Belliago-before-367x489.jpg 367w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><figcaption class=\"wp-element-caption\">Before<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1600\" data-id=\"11179\" src=\"https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1.jpg\" alt=\"\" class=\"wp-image-11179\" srcset=\"https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1.jpg 721w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1-692x1536.jpg 692w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1-640x1420.jpg 640w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1-400x888.jpg 400w, https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-1-1-367x814.jpg 367w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption class=\"wp-element-caption\">After<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>It&#8217;s just not right when the IO in your name isn&#8217;t illuminated. YESCO techs arrived on site at the Bellagio Hotel and Casino in Las Vegas and found there was no power leading to the letters. Quickly found a defective power supply was the problem. No worries. It was easily replaced and the sign is [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-10926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"featured_media_global":[],"featured_image_src":{"landsacpe":["https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-721x445.jpg",721,445,true],"list":["https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after-463x348.jpg",463,348,true],"medium":["https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after.jpg",721,893,false],"full":["https:\/\/www.yesco.com\/lasvegas\/files\/2024\/05\/belliago-after.jpg",721,893,false]},"_links":{"self":[{"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/posts\/10926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/comments?post=10926"}],"version-history":[{"count":1,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/posts\/10926\/revisions"}],"predecessor-version":[{"id":11180,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/posts\/10926\/revisions\/11180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/media\/11176"}],"wp:attachment":[{"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/media?parent=10926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/categories?post=10926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yesco.com\/lasvegas\/wp-json\/wp\/v2\/tags?post=10926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}