{"id":10777,"date":"2023-04-04T10:04:50","date_gmt":"2023-04-04T10:04:50","guid":{"rendered":"https:\/\/www.yesco.com\/losangeles-testing\/storefront-reface\/"},"modified":"2025-01-02T23:10:44","modified_gmt":"2025-01-02T23:10:44","slug":"storefront-reface","status":"publish","type":"post","link":"https:\/\/www.yesco.com\/losangeles\/storefront-reface\/","title":{"rendered":"Storefront Reface"},"content":{"rendered":"\n<p>YESCO refaced the storefront channel letters &#8220;Northgate Market&#8221; and the &#8220;Gonzales&#8221; logo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>YESCO refaced the storefront channel letters &#8220;Northgate Market&#8221; and the &#8220;Gonzales&#8221; logo.<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-10777","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"featured_media_global":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/comments?post=10777"}],"version-history":[{"count":1,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10777\/revisions"}],"predecessor-version":[{"id":11631,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10777\/revisions\/11631"}],"wp:attachment":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/media?parent=10777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/categories?post=10777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/tags?post=10777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}