{"id":10835,"date":"2021-05-25T08:10:23","date_gmt":"2021-05-25T08:10:23","guid":{"rendered":"https:\/\/www.yesco.com\/losangeles-testing\/its-sugar\/"},"modified":"2024-12-31T23:15:00","modified_gmt":"2024-12-31T23:15:00","slug":"its-sugar","status":"publish","type":"post","link":"https:\/\/www.yesco.com\/losangeles\/its-sugar\/","title":{"rendered":"It&#8217;s Sugar"},"content":{"rendered":"\n<p>YESCO provides the experience, quality equipment, and well-trained, certified workers capable of doing the job right.  We had a great time working on this whimsical project for Universal Studios in Los Angeles, California.  <\/p>\n\n\n\n<p>Remember, It&#8217;s Sugar!<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>YESCO provides the experience, quality equipment, and well-trained, certified workers capable of doing the job right. We had a great time working on this whimsical project for Universal Studios in Los Angeles, California. Remember, It&#8217;s Sugar!<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-10835","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"featured_media_global":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/comments?post=10835"}],"version-history":[{"count":1,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10835\/revisions"}],"predecessor-version":[{"id":11578,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/posts\/10835\/revisions\/11578"}],"wp:attachment":[{"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/media?parent=10835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/categories?post=10835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yesco.com\/losangeles\/wp-json\/wp\/v2\/tags?post=10835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}